{"id":65470,"date":"2025-08-18T22:39:46","date_gmt":"2025-08-18T20:39:46","guid":{"rendered":"https:\/\/symmy.com\/integrace\/toptrans-flores\/"},"modified":"2025-08-18T22:39:46","modified_gmt":"2025-08-18T20:39:46","slug":"toptrans-flores","status":"publish","type":"systems","link":"https:\/\/symmy.com\/de\/integrationen\/toptrans-flores\/","title":{"rendered":"TopTrans &#8211; Flores"},"content":{"rendered":"<p>Unsere L\u00f6sungen f\u00fcr die Systemintegration <b><a href=\"\"><\/a><\/b> s <b><a href=\"\"><\/a><\/b> bietet eine zuverl\u00e4ssige Daten\u00fcbertragung f\u00fcr Agenden wie <b>, , und <\/b> mehr. <b>Symmy<\/b> \u00fcberwacht, transformiert und validiert automatisch alle Daten w\u00e4hrend der \u00dcbertragung.<\/p>\n<p>Im Falle eines Fehlers werden Sie sofort benachrichtigt. Sparen Sie Zeit und befreien Sie sich von manuellen Prozessen &#8211; minimieren Sie Fehler durch vollst\u00e4ndige Automatisierung. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere L\u00f6sungen f\u00fcr die Systemintegration s bietet eine zuverl\u00e4ssige Daten\u00fcbertragung f\u00fcr Agenden wie , , und mehr. Symmy \u00fcberwacht, transformiert und validiert automatisch alle Daten w\u00e4hrend der \u00dcbertragung. Im Falle eines Fehlers werden Sie sofort benachrichtigt. Sparen Sie Zeit und befreien Sie sich von manuellen Prozessen &#8211; minimieren Sie Fehler durch vollst\u00e4ndige Automatisierung.<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-65470","systems","type-systems","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/symmy.com\/de\/wp-json\/wp\/v2\/systems\/65470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/symmy.com\/de\/wp-json\/wp\/v2\/systems"}],"about":[{"href":"https:\/\/symmy.com\/de\/wp-json\/wp\/v2\/types\/systems"}],"wp:attachment":[{"href":"https:\/\/symmy.com\/de\/wp-json\/wp\/v2\/media?parent=65470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}